{"id":2540,"date":"2023-10-04T22:10:01","date_gmt":"2023-10-05T03:10:01","guid":{"rendered":"https:\/\/mglashes.ca\/distribution\/?post_type=product&#038;p=2540"},"modified":"2024-10-05T16:58:46","modified_gmt":"2024-10-05T21:58:46","slug":"exfoliant-a-levres-fraise-banane","status":"publish","type":"product","link":"https:\/\/mglashes.ca\/distribution\/produit\/exfoliant-a-levres-fraise-banane\/","title":{"rendered":"Exfoliant \u00e0 l\u00e8vres Fraise Banane"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>Exfoliant pour les l\u00e8vres<\/strong>\u00a01oz<em>\u00a0&#8211; 28g<\/em><\/p>\n<p><strong>La saveur :<\/strong>\u00a0Fraise + Banane<\/p>\n<div class=\"rte product-single__description\">\n<p>G\u00e2tez vos l\u00e8vres avec cette douce friandise ! C&rsquo;est le compl\u00e9ment parfait \u00e0 votre routine de soin des l\u00e8vres&#8230; Le sucre fin donne aux l\u00e8vres une l\u00e9g\u00e8re exfoliation et l&rsquo;huile de jojoba bio + le beurre de karit\u00e9 bio les laissent hydrat\u00e9es, douces et lisses.<\/p>\n<p>Oh et au fait&#8230; C&rsquo;est totalement comestible ! !<\/p>\n<p><b>Directions :<\/b><\/p>\n<p>Du bout des doigts, massez une petite quantit\u00e9 de gommage sur les l\u00e8vres humides.\u00a0L\u00e9chez l&rsquo;exc\u00e9dent ou essuyez-le avec un papier ou une lingette.Conserver dans un endroit frais et sec.<\/p>\n<p><strong>Ingr\u00e9dients :<\/strong><\/p>\n<p>Sucre,\u00a0huile de jojoba biologique, beurre de karit\u00e9 biologique, ar\u00f4mes naturels biologiques, colorants alimentaires.<\/p>\n<p>Le gommage des l\u00e8vres est :<\/p>\n<p>. Fait \u00e0 la main en petits lots<br \/>\n. Naturel<br \/>\n. V\u00e9gan<br \/>\n. Comestible<br \/>\n. Jamais test\u00e9 sur des animaux<br \/>\n. Fabriqu\u00e9 avec des huiles biologiques<br \/>\n. Fait avec amour !<br \/>\n. Fi\u00e8rement canadien<\/p>\n<p>*\u00a0 Aussi offert en duo avec le baume \u00e0 l\u00e8vres<\/p>\n<\/div>\n","protected":false},"featured_media":2541,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[241],"product_tag":[244],"class_list":["post-2540","product","type-product","status-publish","has-post-thumbnail","product_cat-exfoliants-levres","product_tag-exfoliant-levres","product_shipping_class-forfait","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mglashes.ca\/distribution\/wp-json\/wp\/v2\/product\/2540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mglashes.ca\/distribution\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mglashes.ca\/distribution\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mglashes.ca\/distribution\/wp-json\/wp\/v2\/comments?post=2540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mglashes.ca\/distribution\/wp-json\/wp\/v2\/media\/2541"}],"wp:attachment":[{"href":"https:\/\/mglashes.ca\/distribution\/wp-json\/wp\/v2\/media?parent=2540"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mglashes.ca\/distribution\/wp-json\/wp\/v2\/product_brand?post=2540"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mglashes.ca\/distribution\/wp-json\/wp\/v2\/product_cat?post=2540"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mglashes.ca\/distribution\/wp-json\/wp\/v2\/product_tag?post=2540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}